{"id":571,"date":"2025-12-10T15:26:31","date_gmt":"2025-12-10T15:26:31","guid":{"rendered":"https:\/\/www.carmowood.com\/pagina-de-inicio\/"},"modified":"2026-07-20T17:06:24","modified_gmt":"2026-07-20T17:06:24","slug":"pagina-de-inicio","status":"publish","type":"page","link":"https:\/\/www.carmowood.com\/es\/","title":{"rendered":"P\u00e1gina principal"},"content":{"rendered":"    <div class=\"business-areas-block alignfull has-dark-background-color\">\n        <div class=\"carmofarm-carmoform-columns\">\n                            <div class=\"column-wrapper\">\n                    <a href=\"https:\/\/www.carmofarm.com\/\" class=\"column carmofarm\" target=\"_blank\" rel=\"noopener\">\n                        <figure class=\"kb-video media-wrapper pageload-video\" data-settings=\"{&quot;webm&quot;:&quot;&quot;,&quot;mp4&quot;:&quot;https:\\\/\\\/www.carmowood.com\\\/files\\\/uploads\\\/2026\\\/01\\\/CarmoWood_Website_FarmVideo_FullHD.mp4&quot;,&quot;ogg&quot;:&quot;&quot;,&quot;track&quot;:&quot;&quot;,&quot;trackKind&quot;:&quot;&quot;,&quot;trackSrclang&quot;:&quot;&quot;,&quot;autoplay&quot;:false,&quot;loop&quot;:true,&quot;muted&quot;:true,&quot;controls&quot;:false,&quot;preload&quot;:&quot;metadata&quot;}\"><div class=\"video-placeholder\"><img decoding=\"async\" src=\"https:\/\/www.carmowood.com\/files\/uploads\/2025\/12\/1385aacda061544e828a5c8b8358b7ef8ba80819-min-e1769031137707.jpg\" alt=\"\"><\/div><noscript><video playsinline  muted loop><source src=\"https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/CarmoWood_Website_FarmVideo_FullHD.mp4\" type=\"video\/mp4\" \/><\/video><\/noscript><\/figure>                        <div class=\"content-wrapper\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"467\" height=\"81\" viewBox=\"0 0 467 81\"><path fill=\"#31261D\" fill-rule=\"evenodd\" d=\"M40.338,0 C61.921,0 79.598,17.04 80.627,38.374 L76.707,38.374 C75.682,19.2 59.762,3.915 40.338,3.915 C20.254,3.915 3.914,20.255 3.914,40.339 C3.914,60.423 20.254,76.762 40.338,76.762 C59.763,76.762 75.682,61.477 76.707,42.304 L80.627,42.304 C79.598,63.637 61.922,80.677 40.338,80.677 C18.095,80.677 0,62.581 0,40.339 C0,18.096 18.095,0 40.338,0 Z M40.3377,7.2734 C57.6147,7.2734 71.7837,20.8134 72.8037,37.8394 L68.8787,37.8394 C67.8647,22.9744 55.4557,11.1884 40.3377,11.1884 C24.5587,11.1884 11.7217,24.0254 11.7217,39.8054 C11.7217,55.5844 24.5587,68.4214 40.3377,68.4214 C55.4557,68.4214 67.8647,56.6354 68.8787,41.7704 L72.8037,41.7704 C71.7837,58.7954 57.6147,72.3364 40.3377,72.3364 C22.3997,72.3364 7.8067,57.7424 7.8067,39.8054 C7.8067,21.8664 22.3997,7.2734 40.3377,7.2734 Z M40.3377,15.0805 C53.3087,15.0805 63.9707,25.1225 64.9767,37.8395 L61.0517,37.8395 C60.0577,27.2835 51.1487,18.9955 40.3377,18.9955 C28.8637,18.9955 19.5287,28.3305 19.5287,39.8045 C19.5287,51.2795 28.8637,60.6145 40.3377,60.6145 C51.1487,60.6145 60.0577,52.3255 61.0517,41.7695 L64.9767,41.7695 C63.9707,54.4865 53.3087,64.5285 40.3377,64.5285 C26.7047,64.5285 15.6137,53.4375 15.6137,39.8045 C15.6137,26.1725 26.7047,15.0805 40.3377,15.0805 Z M40.3377,22.8876 C49.0007,22.8876 56.1597,29.4346 57.1367,37.8396 L53.1917,37.8396 C52.2407,31.5996 46.8397,26.8026 40.3377,26.8026 C33.1677,26.8026 27.3357,32.6356 27.3357,39.8046 C27.3357,46.9746 33.1677,52.8066 40.3377,52.8066 C46.8397,52.8066 52.2417,48.0106 53.1917,41.7696 L57.1367,41.7696 C56.1597,50.1756 49.0007,56.7216 40.3377,56.7216 C31.0097,56.7216 23.4207,49.1336 23.4207,39.8046 C23.4207,30.4766 31.0097,22.8876 40.3377,22.8876 Z M40.3377,30.6947 C44.6857,30.6947 48.3267,33.7587 49.2277,37.8397 L45.1437,37.8397 C44.3677,35.9467 42.5067,34.6097 40.3377,34.6097 C37.4737,34.6097 35.1427,36.9397 35.1427,39.8047 C35.1427,42.6697 37.4737,44.9997 40.3377,44.9997 C42.5067,44.9997 44.3677,43.6627 45.1437,41.7697 L49.2287,41.7697 C48.3267,45.8507 44.6857,48.9147 40.3377,48.9147 C35.3147,48.9147 31.2277,44.8277 31.2277,39.8047 C31.2277,34.7817 35.3147,30.6947 40.3377,30.6947 Z M310.8008,17.2648 L342.1828,17.2648 L342.1828,24.3628 L318.5938,24.3628 L318.5938,38.4178 L339.0498,38.4178 L339.0498,45.0278 L318.5938,45.0278 L318.5938,63.4668 L310.8008,63.4668 L310.8008,17.2648 Z M366.4633,55.9509 C368.1333,54.9309 369.4423,53.5509 370.3953,51.8129 C371.3453,50.0709 371.8213,48.1579 371.8213,46.0709 C371.8213,43.9839 371.3453,42.0699 370.3953,40.3309 C369.4423,38.5929 368.1213,37.1999 366.4303,36.1559 C364.7353,35.1119 362.9143,34.5919 360.9673,34.5919 C359.0183,34.5919 357.2313,35.0789 355.6103,36.0509 C353.9843,37.0259 352.6993,38.3819 351.7473,40.1219 C350.7963,41.8629 350.3213,43.8449 350.3213,46.0709 C350.3213,48.3439 350.8083,50.3399 351.7813,52.0549 C352.7573,53.7719 354.0543,55.1049 355.6783,56.0559 C357.3033,57.0059 359.0643,57.4829 360.9673,57.4829 C362.9613,57.4829 364.7933,56.9719 366.4633,55.9509 M350.9463,62.0399 C348.3953,60.3939 346.3893,58.1559 344.9303,55.3239 C343.4673,52.4979 342.7373,49.4109 342.7373,46.0709 C342.7373,42.6859 343.4673,39.5779 344.9303,36.7479 C346.3893,33.9189 348.4083,31.6799 350.9823,30.0339 C353.5583,28.3879 356.4213,27.5639 359.5743,27.5639 C362.3123,27.5639 364.8053,28.2249 367.0553,29.5459 C369.3043,30.8689 371.0093,32.6679 372.1703,34.9379 L372.1703,28.6059 L379.4043,28.6059 L379.4043,63.4659 L372.1003,63.4659 L372.1003,57.2039 C370.9863,59.4319 369.3043,61.2049 367.0553,62.5259 C364.8053,63.8489 362.3123,64.5099 359.5743,64.5099 C356.3753,64.5099 353.4983,63.6869 350.9463,62.0399 M385.1114,28.6063 L392.4154,28.6063 L392.4154,35.2863 C393.2974,33.1543 394.6084,31.5053 396.3494,30.3463 C398.0874,29.1863 400.2804,28.6063 402.9234,28.6063 L406.1944,28.6063 L406.1944,35.1483 L402.9234,35.1483 C400.8814,35.1483 399.0964,35.6223 397.5664,36.5743 C396.0344,37.5253 394.8534,38.9043 394.0184,40.7123 C393.1834,42.5233 392.7644,44.7043 392.7644,47.2543 L392.7644,63.4653 L385.1114,63.4653 L385.1114,28.6063 Z M410.5758,28.6063 L417.8128,28.6063 L417.9068,33.4033 C418.2698,32.8613 418.6788,32.3403 419.1348,31.8413 C420.3388,30.5203 421.8348,29.4773 423.6218,28.7113 C425.4078,27.9453 427.3678,27.5633 429.5008,27.5633 C432.7938,27.5633 435.4608,28.4923 437.5018,30.3463 C438.7398,31.4723 439.7388,32.9213 440.4828,34.6953 C441.0628,33.8173 441.6928,33.0173 442.3738,32.2943 C443.9028,30.6703 445.6318,29.4773 447.5568,28.7113 C449.4798,27.9453 451.5098,27.5633 453.6458,27.5633 C457.8198,27.5633 461.0088,28.9443 463.2128,31.7033 C465.4148,34.4633 466.5168,38.5103 466.5168,43.8443 L466.5168,63.4653 L458.9338,63.4653 L458.9338,44.4013 C458.9338,41.1553 458.2728,38.7073 456.9488,37.0603 C455.6278,35.4143 453.8078,34.5923 451.4888,34.5923 C449.8188,34.5923 448.2988,35.0193 446.9308,35.8773 C445.5608,36.7363 444.4608,37.9773 443.6258,39.5983 C442.7908,41.2243 442.3738,43.1253 442.3738,45.3053 L442.3738,63.4653 L434.7878,63.4653 L434.7878,44.4013 C434.7878,41.1553 434.1278,38.7073 432.8058,37.0603 C431.4848,35.4143 429.6858,34.5923 427.4148,34.5923 C425.6978,34.5923 424.1538,35.0193 422.7868,35.8773 C421.4188,36.7363 420.3178,37.9773 419.4828,39.5983 C418.6478,41.2243 418.2288,43.0793 418.2288,45.1663 L418.2288,63.4653 L410.5758,63.4653 L410.5758,28.6063 Z M100.3947,61.2062 C96.6607,59.0502 93.7057,56.1282 91.5257,52.4422 C89.3457,48.7562 88.2567,44.7102 88.2567,40.3042 C88.2567,35.8992 89.3457,31.8522 91.5257,28.1662 C93.7057,24.4792 96.6497,21.5702 100.3597,19.4372 C104.0687,17.3042 108.1267,16.2362 112.5327,16.2362 C116.0107,16.2362 119.3377,16.9092 122.5137,18.2542 C125.6907,19.6002 128.4257,21.6522 130.7217,24.4102 C133.0167,27.1692 134.5127,30.5432 135.2087,34.5312 L125.9577,34.5312 C125.4467,31.3782 123.9057,28.9202 121.3317,27.1572 C118.7587,25.3952 115.7777,24.5142 112.3937,24.5142 C109.5177,24.5142 106.9437,25.1642 104.6727,26.4622 C102.3997,27.7602 100.6037,29.6162 99.2817,32.0262 C97.9597,34.4382 97.2997,37.1982 97.2997,40.3042 C97.2997,43.5042 97.9827,46.3102 99.3517,48.7202 C100.7187,51.1322 102.5617,52.9752 104.8807,54.2502 C107.1987,55.5262 109.7957,56.1632 112.6717,56.1632 C115.9167,56.1632 118.7237,55.3282 121.0887,53.6592 C123.4527,51.9902 125.0527,49.4852 125.8877,46.1472 L135.2087,46.1472 C134.5127,50.1812 133.0277,53.5662 130.7567,56.3022 C128.4847,59.0392 125.7597,61.0792 122.5837,62.4232 C119.4067,63.7682 116.0797,64.4412 112.6027,64.4412 C108.1957,64.4412 104.1267,63.3632 100.3947,61.2062 M160.7011,55.085 C162.2081,54.181 163.4021,52.929 164.2831,51.329 C165.1641,49.729 165.6061,47.98 165.6061,46.077 C165.6061,44.129 165.1641,42.356 164.2831,40.756 C163.4021,39.156 162.1971,37.881 160.6661,36.93 C159.1361,35.981 157.4671,35.505 155.6591,35.505 C153.8501,35.505 152.2151,35.946 150.7551,36.826 C149.2941,37.707 148.1341,38.937 147.2771,40.513 C146.4181,42.09 145.9901,43.921 145.9901,46.008 C145.9901,48.141 146.4301,49.997 147.3111,51.573 C148.1911,53.15 149.3741,54.355 150.8591,55.19 C152.3431,56.024 153.9421,56.442 155.6591,56.442 C157.5131,56.442 159.1941,55.99 160.7011,55.085 M145.3991,62.041 C142.8711,60.395 140.8771,58.157 139.4161,55.328 C137.9561,52.5 137.2261,49.393 137.2261,46.008 C137.2261,42.624 137.9561,39.504 139.4161,36.652 C140.8771,33.8 142.8831,31.551 145.4341,29.905 C147.9831,28.259 150.8591,27.436 154.0581,27.436 C156.6081,27.436 158.9501,28.027 161.0841,29.209 C163.2161,30.392 164.8401,32.004 165.9531,34.044 L165.9531,28.479 L174.3001,28.479 L174.3001,63.467 L165.8841,63.467 L165.8841,57.972 C164.8161,60.013 163.2161,61.613 161.0841,62.771 C158.9501,63.93 156.5851,64.51 153.9891,64.51 C150.7901,64.51 147.9251,63.687 145.3991,62.041 M179.3774,28.479 L187.7244,28.479 L187.7244,34.461 C188.6044,32.56 189.8574,31.087 191.4804,30.044 C193.1034,29.001 195.1674,28.479 197.6714,28.479 L201.0104,28.479 L201.0104,35.992 L197.6714,35.992 C195.7234,35.992 194.0304,36.433 192.5934,37.313 C191.1554,38.194 190.0544,39.481 189.2894,41.174 C188.5244,42.867 188.1414,44.895 188.1414,47.26 L188.1414,63.467 L179.3774,63.467 L179.3774,28.479 Z M204.9046,28.479 L213.1826,28.479 L213.2416,32.954 C213.5706,32.464 213.9446,31.993 214.3646,31.54 C215.5226,30.287 216.9726,29.291 218.7116,28.548 C220.4506,27.808 222.3396,27.436 224.3806,27.436 C227.7196,27.436 230.3976,28.34 232.4156,30.149 C233.6216,31.231 234.6396,32.626 235.3896,34.322 C235.9506,33.509 236.5476,32.767 237.1796,32.096 C238.7096,30.473 240.4026,29.291 242.2576,28.548 C244.1116,27.808 246.0596,27.436 248.1006,27.436 C252.3656,27.436 255.6006,28.826 257.8036,31.609 C260.0056,34.391 261.1076,38.426 261.1076,43.713 L261.1076,63.467 L252.2736,63.467 L252.2736,44.338 C252.2736,41.372 251.6826,39.156 250.4996,37.695 C249.3176,36.235 247.6826,35.505 245.5956,35.505 C244.1116,35.505 242.7446,35.899 241.4926,36.687 C240.2396,37.476 239.2426,38.624 238.5006,40.13 C237.7586,41.638 237.3886,43.389 237.3886,45.382 L237.3886,63.467 L228.6246,63.467 L228.6246,44.338 C228.6246,41.372 228.0336,39.156 226.8506,37.695 C225.6676,36.235 224.0336,35.505 221.9466,35.505 C220.4166,35.505 219.0246,35.899 217.7726,36.687 C216.5216,37.476 215.5226,38.612 214.7826,40.096 C214.0396,41.58 213.6686,43.295 213.6686,45.243 L213.6686,63.467 L204.9046,63.467 L204.9046,28.479 Z M288.4436,55.085 C289.9266,54.181 291.0976,52.941 291.9566,51.364 C292.8136,49.788 293.2436,48.003 293.2436,46.008 C293.2436,44.014 292.8136,42.217 291.9566,40.617 C291.0976,39.018 289.9266,37.777 288.4436,36.896 C286.9586,36.015 285.2666,35.574 283.3656,35.574 C281.5106,35.574 279.8406,36.015 278.3576,36.896 C276.8726,37.777 275.7146,39.018 274.8796,40.617 C274.0456,42.217 273.6276,44.014 273.6276,46.008 C273.6276,48.003 274.0456,49.788 274.8796,51.364 C275.7146,52.941 276.8726,54.181 278.3576,55.085 C279.8406,55.99 281.5106,56.442 283.3656,56.442 C285.2666,56.442 286.9586,55.99 288.4436,55.085 M273.8716,62.041 C271.0646,60.395 268.8626,58.157 267.2626,55.328 C265.6636,52.5 264.8636,49.393 264.8636,46.008 C264.8636,42.624 265.6516,39.504 267.2286,36.652 C268.8046,33.8 271.0076,31.551 273.8366,29.905 C276.6646,28.259 279.8406,27.436 283.3656,27.436 C286.9366,27.436 290.1236,28.259 292.9296,29.905 C295.7346,31.551 297.9386,33.8 299.5376,36.652 C301.1376,39.504 301.9386,42.624 301.9386,46.008 C301.9386,49.393 301.1376,52.5 299.5376,55.328 C297.9386,58.157 295.7346,60.395 292.9296,62.041 C290.1236,63.687 286.9366,64.51 283.3656,64.51 C279.8406,64.51 276.6766,63.687 273.8716,62.041\"\/><\/svg>                                                            <div class=\"carmofarm-btn\">Conoce CarmoFarm<\/div>\n                                                    <\/div>\n                    <\/a>\n\n                                    <\/div>\n                                        <div class=\"column-wrapper\">\n                    <a href=\"https:\/\/www.carmoform.com\/\" class=\"column carmoform\" target=\"_blank\" rel=\"noopener\">\n                        <figure class=\"kb-video media-wrapper pageload-video\" data-settings=\"{&quot;webm&quot;:&quot;&quot;,&quot;mp4&quot;:&quot;https:\\\/\\\/www.carmowood.com\\\/files\\\/uploads\\\/2026\\\/01\\\/CarmoWood_Website_FormVideo_FullHD.mp4&quot;,&quot;ogg&quot;:&quot;&quot;,&quot;track&quot;:&quot;&quot;,&quot;trackKind&quot;:&quot;&quot;,&quot;trackSrclang&quot;:&quot;&quot;,&quot;autoplay&quot;:false,&quot;loop&quot;:true,&quot;muted&quot;:true,&quot;controls&quot;:false,&quot;preload&quot;:&quot;metadata&quot;}\"><div class=\"video-placeholder\"><img decoding=\"async\" src=\"https:\/\/www.carmowood.com\/files\/uploads\/2025\/12\/cd78a2e355c264bfcb62e8f6935f08adacf9d2fe-min.jpg\" alt=\"\"><\/div><noscript><video playsinline  muted loop><source src=\"https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/CarmoWood_Website_FormVideo_FullHD.mp4\" type=\"video\/mp4\" \/><\/video><\/noscript><\/figure>                        <div class=\"content-wrapper\">\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"467\" height=\"81\" viewBox=\"0 0 467 81\"><path fill=\"#31261D\" fill-rule=\"evenodd\" d=\"M40.338,0 C61.921,0 79.598,17.04 80.627,38.374 L76.707,38.374 C75.682,19.2 59.762,3.915 40.338,3.915 C20.254,3.915 3.914,20.255 3.914,40.339 C3.914,60.423 20.254,76.762 40.338,76.762 C59.763,76.762 75.682,61.477 76.707,42.304 L80.627,42.304 C79.598,63.637 61.922,80.677 40.338,80.677 C18.095,80.677 0,62.581 0,40.339 C0,18.096 18.095,0 40.338,0 Z M40.3377,7.2734 C57.6147,7.2734 71.7837,20.8134 72.8037,37.8394 L68.8787,37.8394 C67.8647,22.9744 55.4557,11.1884 40.3377,11.1884 C24.5587,11.1884 11.7217,24.0254 11.7217,39.8054 C11.7217,55.5844 24.5587,68.4214 40.3377,68.4214 C55.4557,68.4214 67.8647,56.6354 68.8787,41.7704 L72.8037,41.7704 C71.7837,58.7954 57.6147,72.3364 40.3377,72.3364 C22.3997,72.3364 7.8067,57.7424 7.8067,39.8054 C7.8067,21.8664 22.3997,7.2734 40.3377,7.2734 Z M40.3377,15.0805 C53.3087,15.0805 63.9707,25.1225 64.9767,37.8395 L61.0517,37.8395 C60.0577,27.2835 51.1487,18.9955 40.3377,18.9955 C28.8637,18.9955 19.5287,28.3305 19.5287,39.8045 C19.5287,51.2795 28.8637,60.6145 40.3377,60.6145 C51.1487,60.6145 60.0577,52.3255 61.0517,41.7695 L64.9767,41.7695 C63.9707,54.4865 53.3087,64.5285 40.3377,64.5285 C26.7047,64.5285 15.6137,53.4375 15.6137,39.8045 C15.6137,26.1725 26.7047,15.0805 40.3377,15.0805 Z M40.3377,22.8876 C49.0007,22.8876 56.1597,29.4346 57.1367,37.8396 L53.1917,37.8396 C52.2407,31.5996 46.8397,26.8026 40.3377,26.8026 C33.1677,26.8026 27.3357,32.6356 27.3357,39.8046 C27.3357,46.9746 33.1677,52.8066 40.3377,52.8066 C46.8397,52.8066 52.2417,48.0106 53.1917,41.7696 L57.1367,41.7696 C56.1597,50.1756 49.0007,56.7216 40.3377,56.7216 C31.0097,56.7216 23.4207,49.1336 23.4207,39.8046 C23.4207,30.4766 31.0097,22.8876 40.3377,22.8876 Z M40.3377,30.6947 C44.6857,30.6947 48.3267,33.7587 49.2277,37.8397 L45.1437,37.8397 C44.3677,35.9467 42.5067,34.6097 40.3377,34.6097 C37.4737,34.6097 35.1427,36.9397 35.1427,39.8047 C35.1427,42.6697 37.4737,44.9997 40.3377,44.9997 C42.5067,44.9997 44.3677,43.6627 45.1437,41.7697 L49.2287,41.7697 C48.3267,45.8507 44.6857,48.9147 40.3377,48.9147 C35.3147,48.9147 31.2277,44.8277 31.2277,39.8047 C31.2277,34.7817 35.3147,30.6947 40.3377,30.6947 Z M100.3947,61.2062 C96.6607,59.0502 93.7057,56.1282 91.5257,52.4422 C89.3457,48.7562 88.2567,44.7102 88.2567,40.3042 C88.2567,35.8992 89.3457,31.8522 91.5257,28.1662 C93.7057,24.4792 96.6497,21.5702 100.3597,19.4372 C104.0687,17.3042 108.1267,16.2362 112.5327,16.2362 C116.0107,16.2362 119.3377,16.9092 122.5137,18.2542 C125.6907,19.6002 128.4257,21.6522 130.7217,24.4102 C133.0167,27.1692 134.5127,30.5432 135.2087,34.5312 L125.9577,34.5312 C125.4467,31.3782 123.9057,28.9202 121.3317,27.1572 C118.7587,25.3952 115.7777,24.5142 112.3937,24.5142 C109.5177,24.5142 106.9437,25.1642 104.6727,26.4622 C102.3997,27.7602 100.6037,29.6162 99.2817,32.0262 C97.9597,34.4382 97.2997,37.1982 97.2997,40.3042 C97.2997,43.5042 97.9827,46.3102 99.3517,48.7202 C100.7187,51.1322 102.5617,52.9752 104.8807,54.2502 C107.1987,55.5262 109.7957,56.1632 112.6717,56.1632 C115.9167,56.1632 118.7237,55.3282 121.0887,53.6592 C123.4527,51.9902 125.0527,49.4852 125.8877,46.1472 L135.2087,46.1472 C134.5127,50.1812 133.0277,53.5662 130.7567,56.3022 C128.4847,59.0392 125.7597,61.0792 122.5837,62.4232 C119.4067,63.7682 116.0797,64.4412 112.6027,64.4412 C108.1957,64.4412 104.1267,63.3632 100.3947,61.2062 M160.7011,55.085 C162.2081,54.181 163.4021,52.929 164.2831,51.329 C165.1641,49.729 165.6061,47.98 165.6061,46.077 C165.6061,44.129 165.1641,42.356 164.2831,40.756 C163.4021,39.156 162.1971,37.881 160.6661,36.93 C159.1361,35.981 157.4671,35.505 155.6591,35.505 C153.8501,35.505 152.2151,35.946 150.7551,36.826 C149.2941,37.707 148.1341,38.937 147.2771,40.513 C146.4181,42.09 145.9901,43.921 145.9901,46.008 C145.9901,48.141 146.4301,49.997 147.3111,51.573 C148.1911,53.15 149.3741,54.355 150.8591,55.19 C152.3431,56.024 153.9421,56.442 155.6591,56.442 C157.5131,56.442 159.1941,55.99 160.7011,55.085 M145.3991,62.041 C142.8711,60.395 140.8771,58.157 139.4161,55.328 C137.9561,52.5 137.2261,49.393 137.2261,46.008 C137.2261,42.624 137.9561,39.504 139.4161,36.652 C140.8771,33.8 142.8831,31.551 145.4341,29.905 C147.9831,28.259 150.8591,27.436 154.0581,27.436 C156.6081,27.436 158.9501,28.027 161.0841,29.209 C163.2161,30.392 164.8401,32.004 165.9531,34.044 L165.9531,28.479 L174.3001,28.479 L174.3001,63.467 L165.8841,63.467 L165.8841,57.972 C164.8161,60.013 163.2161,61.613 161.0841,62.771 C158.9501,63.93 156.5851,64.51 153.9891,64.51 C150.7901,64.51 147.9251,63.687 145.3991,62.041 M179.3774,28.479 L187.7244,28.479 L187.7244,34.461 C188.6044,32.56 189.8574,31.087 191.4804,30.044 C193.1034,29.001 195.1674,28.479 197.6714,28.479 L201.0104,28.479 L201.0104,35.992 L197.6714,35.992 C195.7234,35.992 194.0304,36.433 192.5934,37.313 C191.1554,38.194 190.0544,39.481 189.2894,41.174 C188.5244,42.867 188.1414,44.895 188.1414,47.26 L188.1414,63.467 L179.3774,63.467 L179.3774,28.479 Z M204.9046,28.479 L213.1826,28.479 L213.2416,32.954 C213.5706,32.464 213.9446,31.993 214.3646,31.54 C215.5226,30.287 216.9726,29.291 218.7116,28.548 C220.4506,27.808 222.3396,27.436 224.3806,27.436 C227.7196,27.436 230.3976,28.34 232.4156,30.149 C233.6216,31.231 234.6396,32.626 235.3896,34.322 C235.9506,33.509 236.5476,32.767 237.1796,32.096 C238.7096,30.473 240.4026,29.291 242.2576,28.548 C244.1116,27.808 246.0596,27.436 248.1006,27.436 C252.3656,27.436 255.6006,28.826 257.8036,31.609 C260.0056,34.391 261.1076,38.426 261.1076,43.713 L261.1076,63.467 L252.2736,63.467 L252.2736,44.338 C252.2736,41.372 251.6826,39.156 250.4996,37.695 C249.3176,36.235 247.6826,35.505 245.5956,35.505 C244.1116,35.505 242.7446,35.899 241.4926,36.687 C240.2396,37.476 239.2426,38.624 238.5006,40.13 C237.7586,41.638 237.3886,43.389 237.3886,45.382 L237.3886,63.467 L228.6246,63.467 L228.6246,44.338 C228.6246,41.372 228.0336,39.156 226.8506,37.695 C225.6676,36.235 224.0336,35.505 221.9466,35.505 C220.4166,35.505 219.0246,35.899 217.7726,36.687 C216.5216,37.476 215.5226,38.612 214.7826,40.096 C214.0396,41.58 213.6686,43.295 213.6686,45.243 L213.6686,63.467 L204.9046,63.467 L204.9046,28.479 Z M288.4436,55.085 C289.9266,54.181 291.0976,52.941 291.9566,51.364 C292.8136,49.788 293.2436,48.003 293.2436,46.008 C293.2436,44.014 292.8136,42.217 291.9566,40.617 C291.0976,39.018 289.9266,37.777 288.4436,36.896 C286.9586,36.015 285.2666,35.574 283.3656,35.574 C281.5106,35.574 279.8406,36.015 278.3576,36.896 C276.8726,37.777 275.7146,39.018 274.8796,40.617 C274.0456,42.217 273.6276,44.014 273.6276,46.008 C273.6276,48.003 274.0456,49.788 274.8796,51.364 C275.7146,52.941 276.8726,54.181 278.3576,55.085 C279.8406,55.99 281.5106,56.442 283.3656,56.442 C285.2666,56.442 286.9586,55.99 288.4436,55.085 M273.8716,62.041 C271.0646,60.395 268.8626,58.157 267.2626,55.328 C265.6636,52.5 264.8636,49.393 264.8636,46.008 C264.8636,42.624 265.6516,39.504 267.2286,36.652 C268.8046,33.8 271.0076,31.551 273.8366,29.905 C276.6646,28.259 279.8406,27.436 283.3656,27.436 C286.9366,27.436 290.1236,28.259 292.9296,29.905 C295.7346,31.551 297.9386,33.8 299.5376,36.652 C301.1376,39.504 301.9386,42.624 301.9386,46.008 C301.9386,49.393 301.1376,52.5 299.5376,55.328 C297.9386,58.157 295.7346,60.395 292.9296,62.041 C290.1236,63.687 286.9366,64.51 283.3656,64.51 C279.8406,64.51 276.6766,63.687 273.8716,62.041 M310.8008,17.3714 L342.1828,17.3714 L342.1828,24.4694 L318.5938,24.4694 L318.5938,38.5244 L339.0498,38.5244 L339.0498,45.1344 L318.5938,45.1344 L318.5938,63.5734 L310.8008,63.5734 L310.8008,17.3714 Z M385.1114,28.713 L392.4154,28.713 L392.4154,35.393 C393.2974,33.261 394.6084,31.612 396.3494,30.453 C398.0874,29.293 400.2804,28.713 402.9234,28.713 L406.1944,28.713 L406.1944,35.255 L402.9234,35.255 C400.8814,35.255 399.0964,35.729 397.5664,36.681 C396.0344,37.632 394.8534,39.011 394.0184,40.819 C393.1834,42.63 392.7644,44.811 392.7644,47.361 L392.7644,63.572 L385.1114,63.572 L385.1114,28.713 Z M410.5758,28.713 L417.8128,28.713 L417.9068,33.51 C418.2698,32.968 418.6788,32.447 419.1348,31.948 C420.3388,30.627 421.8348,29.584 423.6218,28.818 C425.4078,28.052 427.3678,27.67 429.5008,27.67 C432.7938,27.67 435.4608,28.599 437.5018,30.453 C438.7398,31.579 439.7388,33.028 440.4828,34.802 C441.0628,33.924 441.6928,33.124 442.3738,32.401 C443.9028,30.777 445.6318,29.584 447.5568,28.818 C449.4798,28.052 451.5098,27.67 453.6458,27.67 C457.8198,27.67 461.0088,29.051 463.2128,31.81 C465.4148,34.57 466.5168,38.617 466.5168,43.951 L466.5168,63.572 L458.9338,63.572 L458.9338,44.508 C458.9338,41.262 458.2728,38.814 456.9488,37.167 C455.6278,35.522 453.8078,34.699 451.4888,34.699 C449.8188,34.699 448.2988,35.126 446.9308,35.984 C445.5608,36.843 444.4608,38.084 443.6258,39.705 C442.7908,41.331 442.3738,43.232 442.3738,45.412 L442.3738,63.572 L434.7878,63.572 L434.7878,44.508 C434.7878,41.262 434.1278,38.814 432.8058,37.167 C431.4848,35.522 429.6858,34.699 427.4148,34.699 C425.6978,34.699 424.1538,35.126 422.7868,35.984 C421.4188,36.843 420.3178,38.084 419.4828,39.705 C418.6478,41.331 418.2288,43.186 418.2288,45.273 L418.2288,63.572 L410.5758,63.572 L410.5758,28.713 Z M366.4093,56.0062 C368.0273,55.0102 369.3133,53.6452 370.2623,51.9102 C371.2093,50.1752 371.6843,48.2422 371.6843,46.1122 C371.6843,43.9372 371.2093,41.9942 370.2623,40.2812 C369.3133,38.5692 368.0273,37.2162 366.4093,36.2202 C364.7873,35.2262 362.9613,34.7282 360.9243,34.7282 C358.9333,34.7282 357.1163,35.2262 355.4743,36.2202 C353.8313,37.2162 352.5473,38.5692 351.6213,40.2812 C350.6963,41.9942 350.2333,43.9372 350.2333,46.1122 C350.2333,48.2422 350.6963,50.1752 351.6213,51.9102 C352.5473,53.6452 353.8313,55.0102 355.4743,56.0062 C357.1163,57.0022 358.9333,57.4982 360.9243,57.4982 C362.9613,57.4982 364.7873,57.0022 366.4093,56.0062 M351.5513,62.0452 C348.7743,60.4042 346.6003,58.1712 345.0263,55.3472 C343.4533,52.5252 342.6653,49.4462 342.6653,46.1122 C342.6653,42.7352 343.4413,39.6332 344.9913,36.8092 C346.5413,33.9872 348.7163,31.7542 351.5163,30.1112 C354.3173,28.4692 357.4523,27.6462 360.9243,27.6462 C364.3963,27.6462 367.5203,28.4692 370.2973,30.1112 C373.0723,31.7542 375.2613,33.9872 376.8573,36.8092 C378.4543,39.6332 379.2523,42.7352 379.2523,46.1122 C379.2523,49.4462 378.4543,52.5252 376.8573,55.3472 C375.2613,58.1712 373.0723,60.4042 370.2973,62.0452 C367.5203,63.6892 364.3963,64.5092 360.9243,64.5092 C357.4523,64.5092 354.3293,63.6892 351.5513,62.0452\"\/><\/svg>                            <div class=\"carmoform-btn\">Conoce CarmoForm<\/div>\n                        <\/div>\n                    <\/a>\n\n                                    <\/div>\n                    <\/div>\n    <\/div>\n\n\n\n<div class=\"wp-block-kobu-custom-blocks-section-wrapper alignfull kobu-section has-background has-lightbrown-background-color\">\n<div class=\"wp-block-kobu-custom-blocks-responsive-spacer responsive-spacer size-large\"><\/div>\n\n\n\n<div class=\"wp-block-columns two-columns-wide-left alignmedium is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-playfair-display-font-family has-extra-large-font-size wp-block-paragraph\">As\u00ed como la madera, la resiliencia est\u00e1 en nuestra esencia.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Con valores comunes profundamente arraigados, como la resiliencia, nos comprometemos a superar la prueba del tiempo y a renovarnos, sin perder la conexi\u00f3n con nuestra esencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que la madera se ramifica, CarmoWood tambi\u00e9n est\u00e1 creciendo, dividi\u00e9ndose en dos \u00e1reas: CarmoFarm y CarmoForm.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.carmowood.com\/es\/carmowood\/que-hacemos\/\">M\u00e1s informaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-kobu-custom-blocks-responsive-spacer responsive-spacer size-large\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-kobu-custom-blocks-section-wrapper alignfull kobu-section wood-parallax parallax-01\"><noscript class=\"loading-lazy\">\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/875ac34cd76f7b1ad247a2f8e84f2f8bb2cb3bee-min-edited-1024x576.jpg\" alt=\"\" class=\"wp-image-586\" srcset=\"https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/875ac34cd76f7b1ad247a2f8e84f2f8bb2cb3bee-min-edited-1024x576.jpg 1024w, https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/875ac34cd76f7b1ad247a2f8e84f2f8bb2cb3bee-min-edited-300x169.jpg 300w, https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/875ac34cd76f7b1ad247a2f8e84f2f8bb2cb3bee-min-edited-768x432.jpg 768w, https:\/\/www.carmowood.com\/files\/uploads\/2026\/01\/875ac34cd76f7b1ad247a2f8e84f2f8bb2cb3bee-min-edited.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/noscript><\/div>\n\n\n\n<div class=\"wp-block-kobu-custom-blocks-responsive-spacer responsive-spacer size-large\"><\/div>\n\n\n<div class=\"heading-cta-block alignfull\">\n            <h2>Obras CarmoFarm<\/h2>\n                        <a class=\"arrow-cta\" href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/\" target=\"_blank\" rel=\"noopener\">m\u00e1s obras <span class=\"arrow-btn\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\"><g fill=\"none\"><path stroke=\"#ECEBE3\" stroke-linejoin=\"square\" d=\"M51.5,26 C51.5,40.0832611 40.0832611,51.5 26,51.5 C11.9167389,51.5 0.5,40.0832611 0.5,26 C0.5,12.8873878 10.4439181,1.94664295 23.392169,0.631676497 L26.0252157,0.499363805 C40.0832611,0.500000001 51.5,11.9167389 51.5,26 Z\"\/><g class=\"arrow-group\" stroke=\"#ECEBE3\" transform=\"translate(18 18)\"><polyline points=\"4.003 1.5 14.5 1.5 14.5 12\"\/><line x1=\"1.5\" x2=\"14.5\" y1=\"14.5\" y2=\"1.5\"\/><\/g><\/g><\/svg><\/span><\/a>\n            <\/div>\n\n    <div class=\"projects-list-block alignfull\">\n        <div class=\"projects slider\">\n            \t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/?categoria-projeto=430\" target=\"_blank\" rel=\"noopener\">Fruticultores<\/a> <a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/\" target=\"_blank\" rel=\"noopener\">CarmoFarm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Palmela<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/huerto-de-kiwis\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Pomar-de-kiwi_Castledynasty-768x432.jpg\" srcset=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Pomar-de-kiwi_Castledynasty-768x432.jpg 768w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Pomar-de-kiwi_Castledynasty-300x169.jpg 300w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Pomar-de-kiwi_Castledynasty-1024x576.jpg 1024w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Pomar-de-kiwi_Castledynasty-1536x864.jpg 1536w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Pomar-de-kiwi_Castledynasty-2048x1152.jpg 2048w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Pomar de kiwi com estrutura parral e rede antigranizo\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Huerto de Kiwis<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/?categoria-projeto=432\" target=\"_blank\" rel=\"noopener\">Vallas<\/a> <a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/\" target=\"_blank\" rel=\"noopener\">CarmoFarm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Albernoa, Beja<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/valla-rustic\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Carmo_-316-768x512.jpg\" srcset=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Carmo_-316-768x512.jpg 768w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Carmo_-316-300x200.jpg 300w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Carmo_-316-1024x683.jpg 1024w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Carmo_-316-1536x1024.jpg 1536w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Carmo_-316-2048x1365.jpg 2048w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Veda\u00e7\u00e3o Rustic em madeira tratada CarmoFarm\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Valla Rustic<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/?categoria-projeto=431\" target=\"_blank\" rel=\"noopener\">Olivares<\/a> <a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/\" target=\"_blank\" rel=\"noopener\">CarmoFarm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Beja<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/olivar\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Olival_Aggraria-768x509.webp\" srcset=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Olival_Aggraria-768x509.webp 768w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Olival_Aggraria-300x199.webp 300w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Olival_Aggraria-1024x678.webp 1024w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Olival_Aggraria-1536x1018.webp 1536w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Olival_Aggraria.webp 1920w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Projeto de olival Aggraria com postes met\u00e1licos e cabeceiras em madeira\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Aggraria<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/?categoria-projeto=433\" target=\"_blank\" rel=\"noopener\">Vi\u00f1edos<\/a> <a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/\" target=\"_blank\" rel=\"noopener\">CarmoFarm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Beja<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/herdade-dos-grous\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Vinha-em-Madeira_Herdade-dos-Grous-768x432.webp\" srcset=\"https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Vinha-em-Madeira_Herdade-dos-Grous-768x432.webp 768w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Vinha-em-Madeira_Herdade-dos-Grous-300x169.webp 300w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Vinha-em-Madeira_Herdade-dos-Grous-1024x576.webp 1024w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Vinha-em-Madeira_Herdade-dos-Grous-1536x864.webp 1536w, https:\/\/www.carmofarm.com\/files\/uploads\/2026\/01\/Vinha-em-Madeira_Herdade-dos-Grous.webp 1920w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Projeto de vinha na Herdade dos Grous\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Herdade dos Grous<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/?categoria-projeto=433\" target=\"_blank\" rel=\"noopener\">Vi\u00f1edos<\/a> <a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/categoria\/carmofarm\/\" target=\"_blank\" rel=\"noopener\">CarmoFarm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Albernoa, Beja<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmofarm.com\/es\/portefolio\/vinha-com-rede\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmofarm.com\/files\/uploads\/2025\/12\/Vinha-com-Rede_Herdade-da-Malhadinha-Nova-768x431.webp\" srcset=\"https:\/\/www.carmofarm.com\/files\/uploads\/2025\/12\/Vinha-com-Rede_Herdade-da-Malhadinha-Nova-768x431.webp 768w, https:\/\/www.carmofarm.com\/files\/uploads\/2025\/12\/Vinha-com-Rede_Herdade-da-Malhadinha-Nova-300x168.webp 300w, https:\/\/www.carmofarm.com\/files\/uploads\/2025\/12\/Vinha-com-Rede_Herdade-da-Malhadinha-Nova-1024x574.webp 1024w, https:\/\/www.carmofarm.com\/files\/uploads\/2025\/12\/Vinha-com-Rede_Herdade-da-Malhadinha-Nova-1536x862.webp 1536w, https:\/\/www.carmofarm.com\/files\/uploads\/2025\/12\/Vinha-com-Rede_Herdade-da-Malhadinha-Nova.webp 1920w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Vinha com rede antip\u00e1ssaro e estruturas em madeira CarmoFarm\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Vi\u00f1edo con red antip\u00e1jaros<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n        <\/div>\n    <\/div>\n\n\n\n<div class=\"wp-block-kobu-custom-blocks-responsive-spacer responsive-spacer size-large\"><\/div>\n\n\n<div class=\"heading-cta-block alignfull\">\n            <h2>Obras CarmoForm<\/h2>\n                        <a class=\"arrow-cta\" href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/\" target=\"_blank\" rel=\"noopener\">m\u00e1s obras <span class=\"arrow-btn\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\"><g fill=\"none\"><path stroke=\"#ECEBE3\" stroke-linejoin=\"square\" d=\"M51.5,26 C51.5,40.0832611 40.0832611,51.5 26,51.5 C11.9167389,51.5 0.5,40.0832611 0.5,26 C0.5,12.8873878 10.4439181,1.94664295 23.392169,0.631676497 L26.0252157,0.499363805 C40.0832611,0.500000001 51.5,11.9167389 51.5,26 Z\"\/><g class=\"arrow-group\" stroke=\"#ECEBE3\" transform=\"translate(18 18)\"><polyline points=\"4.003 1.5 14.5 1.5 14.5 12\"\/><line x1=\"1.5\" x2=\"14.5\" y1=\"14.5\" y2=\"1.5\"\/><\/g><\/g><\/svg><\/span><\/a>\n            <\/div>\n\n    <div class=\"projects-list-block alignfull\">\n        <div class=\"projects slider\">\n            \t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/?categoria-projeto=462\" target=\"_blank\" rel=\"noopener\">Hosteler\u00eda<\/a> <a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/\" target=\"_blank\" rel=\"noopener\">CarmoForm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Comporta, Portugal<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/jncquoi-beach-club\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/JNcQUOI-Beach-Club-768x546.webp\" srcset=\"https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/JNcQUOI-Beach-Club-768x546.webp 768w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/JNcQUOI-Beach-Club-300x213.webp 300w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/JNcQUOI-Beach-Club-1024x728.webp 1024w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/JNcQUOI-Beach-Club-1536x1092.webp 1536w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/JNcQUOI-Beach-Club.webp 1920w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"JNcQUOI Beach Club\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">JNcQUOI Beach Club<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/?categoria-projeto=461\" target=\"_blank\" rel=\"noopener\">Viviendas<\/a> <a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/\" target=\"_blank\" rel=\"noopener\">CarmoForm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Vilamoura, Algarve, Portugal<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/sand-villas-arcaya\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/Arcaya_Casa_Sand-1-768x575.webp\" srcset=\"https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/Arcaya_Casa_Sand-1-768x575.webp 768w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/Arcaya_Casa_Sand-1-300x225.webp 300w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/Arcaya_Casa_Sand-1-1024x767.webp 1024w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/Arcaya_Casa_Sand-1-1536x1150.webp 1536w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/Arcaya_Casa_Sand-1.webp 1920w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Sand Villas Arcaya\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Sand Villas Arcaya<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/?categoria-projeto=462\" target=\"_blank\" rel=\"noopener\">Hosteler\u00eda<\/a> <a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/\" target=\"_blank\" rel=\"noopener\">CarmoForm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Comporta, Portugal<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/hotel-sublime-comporta\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/madeiras-tratadas-e-derivados-revestimentos-14-768x433.png\" srcset=\"https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/madeiras-tratadas-e-derivados-revestimentos-14-768x433.png 768w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/madeiras-tratadas-e-derivados-revestimentos-14-300x169.png 300w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/madeiras-tratadas-e-derivados-revestimentos-14-1024x578.png 1024w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/madeiras-tratadas-e-derivados-revestimentos-14.png 1400w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Hotel Sublime Comporta\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Hotel Sublime Comporta<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/?categoria-projeto=460\" target=\"_blank\" rel=\"noopener\">Edif\u00edcios altos e oficinas<\/a> <a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/\" target=\"_blank\" rel=\"noopener\">CarmoForm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Lisboa<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/redbridge-international-school\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1-768x768.webp\" srcset=\"https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1-768x768.webp 768w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1-300x300.webp 300w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1-1024x1024.webp 1024w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1-150x150.webp 150w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1-1536x1536.webp 1536w, https:\/\/www.carmoform.com\/files\/uploads\/2025\/12\/redbridge1.webp 1600w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Redbridge International School\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Redbridge International School<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t<div class=\"article list-project\">\n\t\t<div class=\"project-info\">\n\t\t\t<div class=\"categories\"><a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/?categoria-projeto=464\" target=\"_blank\" rel=\"noopener\">Pasarelas<\/a> <a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/categoria\/carmoform\/\" target=\"_blank\" rel=\"noopener\">CarmoForm<\/a><\/div>\t\t\t\t\t\t\t<div class=\"location\">Arouca<\/div>\n\t\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/www.carmoform.com\/es\/portefolio\/passadicos-do-paiva\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<div class=\"img-wrapper\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/PASSADICOS_DO_PAIVA-768x688.webp\" srcset=\"https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/PASSADICOS_DO_PAIVA-768x688.webp 768w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/PASSADICOS_DO_PAIVA-300x269.webp 300w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/PASSADICOS_DO_PAIVA-1024x918.webp 1024w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/PASSADICOS_DO_PAIVA-1536x1376.webp 1536w, https:\/\/www.carmoform.com\/files\/uploads\/2026\/01\/PASSADICOS_DO_PAIVA.webp 1607w\" sizes=\"(min-width: 993px) 33vw, (min-width: 601px) 50vw, 100vw\" alt=\"Passadi\u00e7os do Paiva\" class=\"coverimg\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"post-title\">Passadi\u00e7os do Paiva<\/h3>\n\t\t\t\t<div class=\"diagonal-arrow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\"><g fill=\"none\" fill-rule=\"evenodd\" stroke=\"#31261D\" transform=\"translate(.6 .6)\"><polyline stroke-width=\"2\" points=\"2.4 .4 10.4 .4 10.4 8.4\"\/><line x1=\".4\" x2=\"10.4\" y1=\"10.4\" y2=\".4\" stroke-width=\"2\"\/><\/g><\/svg><\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/homepage.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-571","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/pages\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/comments?post=571"}],"version-history":[{"count":7,"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/pages\/571\/revisions"}],"predecessor-version":[{"id":14591,"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/pages\/571\/revisions\/14591"}],"wp:attachment":[{"href":"https:\/\/www.carmowood.com\/es\/wp-json\/wp\/v2\/media?parent=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}